{"id":5143,"date":"2015-08-27T10:05:37","date_gmt":"2015-08-27T08:05:37","guid":{"rendered":"http:\/\/qblades.nl\/homepage\/?lang=de"},"modified":"2026-05-12T08:47:52","modified_gmt":"2026-05-12T06:47:52","slug":"homepage","status":"publish","type":"page","link":"https:\/\/qblades.nl\/de\/","title":{"rendered":"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter"},"content":{"rendered":"<div id='av-layout-grid-1'  class='av-layout-grid-container av-av_layout_row-fbf9d6357c568be3994adf2f8433b133 entry-content-wrapper main_color av-flex-cells  avia-builder-el-0  el_before_av_one_fourth  avia-builder-el-first   container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m7itp578-1c425e1452b9a783c5b61c3a4f1fe9ed\">\n.flex_cell.av-m7itp578-1c425e1452b9a783c5b61c3a4f1fe9ed{\nvertical-align:top;\n}\n.responsive #top #wrap_all .flex_cell.av-m7itp578-1c425e1452b9a783c5b61c3a4f1fe9ed{\npadding:0px 0px 0px 0px !important;\n}\n<\/style>\n<div class='flex_cell av-m7itp578-1c425e1452b9a783c5b61c3a4f1fe9ed av-gridrow-cell av_one_full no_margin  avia-builder-el-1  avia-builder-el-no-sibling  av-zero-padding'  ><div class='flex_cell_inner'><section  class='av_textblock_section av-m7itpirv-474ed821082b0dac16c86fb6dc945ef2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><div><\/div>\n<\/div><\/section>\n<\/div><\/div>\n<\/div><div id='after_grid_row_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5143'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-av_one_fourth-bea2f9001043b2450f2ac894d1b6393b av_one_fourth  avia-builder-el-3  el_after_av_layout_row  el_before_av_one_fourth  avia-builder-el-first  first flex_column_div  '     ><section  class='av_textblock_section av-mirkf9uz-5e006697bfc3bf16b707dee7fbd562d5 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul class=\"uspul\">\n<li>\n<h3>Die L\u00f6sung f\u00fcr alle Multitools<\/h3>\n<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<div  class='flex_column av-av_one_fourth-4b43c9b03dde107542944c23c0a53a7c av_one_fourth  avia-builder-el-5  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div  '     ><section  class='av_textblock_section av-mirkktm5-ec9bc31d11f090f301ee692bb0e29a86 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul class=\"uspul\">\n<li>\n<h3>Jetzt auch mit Stichs\u00e4geblatter und S\u00e4bels\u00e4geblatter<\/h3>\n<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<div  class='flex_column av-av_one_fourth-4b43c9b03dde107542944c23c0a53a7c av_one_fourth  avia-builder-el-7  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div  '     ><section  class='av_textblock_section av-mirkmqjp-563493f4f54a1f5622bd8d654a527f9a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul class=\"uspul\">\n<li>\n<h3>100 % plastikfrei<\/h3>\n<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<div  class='flex_column av-av_one_fourth-4b43c9b03dde107542944c23c0a53a7c av_one_fourth  avia-builder-el-9  el_after_av_one_fourth  el_before_av_section  avia-builder-el-last  flex_column_div  '     ><section  class='av_textblock_section av-mirkna47-d6c2e8a7b49e1ef158ba7c2103742983 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul class=\"uspul\">\n<li>\n<h3>Schneller Versand<\/h3>\n<\/li>\n<\/ul>\n<\/div><\/section><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-9cd11513755730b77956f1da84b879cf\">\n.avia-section.av-av_section-9cd11513755730b77956f1da84b879cf{\nbackground-color:#3c3c3b;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-av_section-9cd11513755730b77956f1da84b879cf alternate_color avia-section-default avia-no-border-styling  avia-builder-el-11  el_after_av_one_fourth  el_before_av_hr  avia-bg-style-parallax container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5143'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mhuerqs7-73817a37eaf0e549da8900397d5a3c37\">\n#top .av_textblock_section.av-mhuerqs7-73817a37eaf0e549da8900397d5a3c37 .avia_textblock{\ncolor:#ffffff;\n}\n<\/style>\n<section  class='av_textblock_section av-mhuerqs7-73817a37eaf0e549da8900397d5a3c37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Die neue Brosch\u00fcre zur Kreiss\u00e4ge ist fertig.<\/h2>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-43639eb3b16efaf187ad06602748df50\">\n#top .flex_column.av-av_one_fifth-43639eb3b16efaf187ad06602748df50{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-av_one_fifth-43639eb3b16efaf187ad06602748df50{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-av_one_fifth-43639eb3b16efaf187ad06602748df50{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-43639eb3b16efaf187ad06602748df50 av_one_fifth  avia-builder-el-13  el_after_av_textblock  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b\">\n#top .flex_column.av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b av_three_fifth  avia-builder-el-14  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><p><div  class='avia-button-wrap av-mhues1wv-ff350ae30a1d42f8b9ada8546e97188e-wrap avia-button-center  avia-builder-el-15  el_before_av_textblock  avia-builder-el-first '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mhues1wv-ff350ae30a1d42f8b9ada8546e97188e\">\n#top #wrap_all .avia-button.av-mhues1wv-ff350ae30a1d42f8b9ada8546e97188e{\nbackground-color:#ffffff;\nborder-color:#ffffff;\ncolor:#e30615;\ntransition:all 0.4s ease-in-out;\nmargin:30px 0 15px 0;\n}\n<\/style>\n<a href='https:\/\/qblades.nl\/qcz-brochure\/' class='avia-button av-mhues1wv-ff350ae30a1d42f8b9ada8546e97188e av-link-btn avia-icon_select-yes-right-icon avia-size-x-large avia-position-center' target=\"_blank\" rel=\"noopener noreferrer\"><span class='avia_iconbox_title' >Katalog online ansehen<\/span><span class='avia_button_icon avia_button_icon_right' aria-hidden='true' data-av_icon='\ue86b' data-av_iconfont='entypo-fontello'><\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mhueseqm-37110ba933d20efa4b2d7b635336a44e\">\n#top .av_textblock_section.av-mhueseqm-37110ba933d20efa4b2d7b635336a44e .avia_textblock{\ncolor:#ffffff;\ntext-align:center;\n}\n<\/style>\n<section  class='av_textblock_section av-mhueseqm-37110ba933d20efa4b2d7b635336a44e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/02\/QB_QCZ_Brochure2026.pdf\" target=\"_blank\" rel=\"noopener\">Als PDF herunterladen<\/a><\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-49f6e875884219cf77c24341e550af53\">\n#top .flex_column.av-av_one_fifth-49f6e875884219cf77c24341e550af53{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-av_one_fifth-49f6e875884219cf77c24341e550af53{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-av_one_fifth-49f6e875884219cf77c24341e550af53{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-49f6e875884219cf77c24341e550af53 av_one_fifth  avia-builder-el-17  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5143'><div class='entry-content-wrapper clearfix'><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k235g854-85ede80861adb8770086b3e3c2d2430f\">\n#top .hr.av-k235g854-85ede80861adb8770086b3e3c2d2430f{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-k235g854-85ede80861adb8770086b3e3c2d2430f .hr-inner{\nwidth:50px;\n}\n<\/style>\n<div  class='hr av-k235g854-85ede80861adb8770086b3e3c2d2430f hr-custom  avia-builder-el-18  el_after_av_section  el_before_av_one_full  avia-builder-el-first  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-none'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc5wmppo-8b4c5b304375ace256e12176968394f7\">\n#top .flex_column.av-kc5wmppo-8b4c5b304375ace256e12176968394f7{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-kc5wmppo-8b4c5b304375ace256e12176968394f7{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-kc5wmppo-8b4c5b304375ace256e12176968394f7{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-kc5wmppo-8b4c5b304375ace256e12176968394f7 av_one_full  avia-builder-el-19  el_after_av_hr  el_before_av_one_fourth  first no_margin flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-kc5w0jvj-c9ff77f4559b0950e05ce7d8330d467b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1 style=\"text-align: center;\">Sortiment per Aufnahme<\/h1>\n<\/div><\/section><\/div>\n<div class='flex_column_table av-phcysb-b328dc647aa450f52232664289ee48f7 sc-av_one_fourth av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-phcysb-b328dc647aa450f52232664289ee48f7\">\n.flex_column.av-phcysb-b328dc647aa450f52232664289ee48f7{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\nbackground-color:#efefef;\n}\n<\/style>\n<div  class='flex_column av-phcysb-b328dc647aa450f52232664289ee48f7 av_one_fourth  avia-builder-el-21  el_after_av_one_full  el_before_av_one_fourth  first flex_column_table_cell av-equal-height-column av-align-top avia-full-stretch  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc4h2yos-9daf5c5ea04bf859835a0a5b5b31f781\">\n.avia-image-container.av-kc4h2yos-9daf5c5ea04bf859835a0a5b5b31f781 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc4h2yos-9daf5c5ea04bf859835a0a5b5b31f781 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc4h2yos-9daf5c5ea04bf859835a0a5b5b31f781 av-styling- av-img-linked avia-align-left  avia-builder-el-22  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"\/de\/product-categorie\/sl-slm\/\" class='avia_image '  aria-label='MT_overview_SL'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-21668 avia-img-lazy-loading-not-21668 avia_image ' src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SL.png\" alt='' title='MT_overview_SL'  height=\"350\" width=\"510\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SL.png 510w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SL-300x206.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SL-450x309.png 450w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97\">\n#top .av-special-heading.av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97{\npadding-bottom:10px;\nfont-size:35px;\n}\nbody .av-special-heading.av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97 .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-kz6rz1iz-b36f46594d76ab754bee851a9112cc97 av-special-heading-h2 blockquote modern-quote  avia-builder-el-23  el_after_av_image  el_before_av_hr  av-inherit-size av-linked-heading'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  ><a class=\"av-heading-link\" href=\"\/de\/product-categorie\/sl-slm\/\" >SL\/SLP\/SLM<\/a><\/h2><div class='av-subheading av-subheading_below'><p>Fein Multimaster &amp; Multitalent, Bosch (Starlock)<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc66yi4p-1b6bfc73d5ea3f444eae7bba930a221a\">\n#top .hr.hr-invisible.av-kc66yi4p-1b6bfc73d5ea3f444eae7bba930a221a{\nheight:37px;\n}\n<\/style>\n<div  class='hr av-kc66yi4p-1b6bfc73d5ea3f444eae7bba930a221a hr-invisible  avia-builder-el-24  el_after_av_heading  el_before_av_button '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap av-kc5uymfv-90564a0e1957d9af868fff9f3a6fcd1d-wrap avia-button-left  avia-builder-el-25  el_after_av_hr  el_before_av_iconlist '><a href='\/de\/product-categorie\/sl-slm\/'  class='avia-button av-kc5uymfv-90564a0e1957d9af868fff9f3a6fcd1d av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-left avia-color-theme-color'  ><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >SL\/SLP\/SLM Aufnahme<\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a\">\n#top .avia-icon-list-container.av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a .iconlist_icon{\ncolor:#b02b2c;\n}\n<\/style>\n<div  class='avia-icon-list-container av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a  avia-builder-el-26  el_after_av_button  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a avia-iconlist-animate'>\n<li><a href='\/de\/product-categorie\/sl-slm\/sl-slm-hout\/' title='SL\/SLM Holz'  class='iconlist_icon av-av_iconlist_item-e5b591e33ce485d001411cd5b7096c07 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sl-slm\/sl-slm-hout\/' title='SL\/SLM Holz'>SL\/SLM Holz<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sl-slm\/sl-slm-hout-metaal\/' title='SL\/SLM Holz\/Metall'  class='iconlist_icon av-av_iconlist_item-65284a4945f211fa4b06a53b9ed1ca01 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sl-slm\/sl-slm-hout-metaal\/' title='SL\/SLM Holz\/Metall'>SL\/SLM Holz\/Metall<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sl-slm\/sl-slm-beton-steen\/' title='SL\/SLM Beton\/Stein'  class='iconlist_icon av-av_iconlist_item-06162c51029f9203359c4ad94cb4135e avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sl-slm\/sl-slm-beton-steen\/' title='SL\/SLM Beton\/Stein'>SL\/SLM Beton\/Stein<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sl-slm\/sl-slm-kit-lijm\/' title='SL\/SLM Kitt\/Leim'  class='iconlist_icon av-av_iconlist_item-802c10c96ac93fcd8b4dab64dfbe7927 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sl-slm\/sl-slm-kit-lijm\/' title='SL\/SLM Kitt\/Leim'>SL\/SLM Kitt\/Leim<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sl-slm\/sl-slm-schuren\/' title='SL\/SLM Schleifen'  class='iconlist_icon av-av_iconlist_item-f1f878721ecd2afb948380df39bc40f0 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sl-slm\/sl-slm-schuren\/' title='SL\/SLM Schleifen'>SL\/SLM Schleifen<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sl-slm\/sl-slm-sets\/' title='SL\/SLM Sets'  class='iconlist_icon av-av_iconlist_item-db7ae26b51b69e7449974a320faab830 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sl-slm\/sl-slm-sets\/' title='SL\/SLM Sets'>SL\/SLM Sets<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n<div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-phcysb-3ff94ca8f5e095b9eab04eb721aa5342\">\n.flex_column.av-phcysb-3ff94ca8f5e095b9eab04eb721aa5342{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\nbackground-color:#efefef;\n}\n<\/style>\n<div  class='flex_column av-phcysb-3ff94ca8f5e095b9eab04eb721aa5342 av_one_fourth  avia-builder-el-27  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_table_cell av-equal-height-column av-align-top avia-full-stretch  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc4h2yos-6cdb07a218e6319471185abfc64571b6\">\n.avia-image-container.av-kc4h2yos-6cdb07a218e6319471185abfc64571b6 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc4h2yos-6cdb07a218e6319471185abfc64571b6 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc4h2yos-6cdb07a218e6319471185abfc64571b6 av-styling- av-img-linked avia-align-left  avia-builder-el-28  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"\/de\/product-categorie\/dw\/\" class='avia_image '  aria-label='MT_overview_DW'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-21660 avia-img-lazy-loading-not-21660 avia_image ' src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_DW.png\" alt='' title='MT_overview_DW'  height=\"350\" width=\"510\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_DW.png 510w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_DW-300x206.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_DW-450x309.png 450w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-a42eb814733e1475e01fe0f94a401759\">\n#top .av-special-heading.av-av_heading-a42eb814733e1475e01fe0f94a401759{\npadding-bottom:10px;\nfont-size:35px;\n}\nbody .av-special-heading.av-av_heading-a42eb814733e1475e01fe0f94a401759 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-a42eb814733e1475e01fe0f94a401759 .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-av_heading-a42eb814733e1475e01fe0f94a401759 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-a42eb814733e1475e01fe0f94a401759 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-a42eb814733e1475e01fe0f94a401759 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-a42eb814733e1475e01fe0f94a401759 av-special-heading-h2 blockquote modern-quote  avia-builder-el-29  el_after_av_image  el_before_av_hr  av-inherit-size av-linked-heading'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  ><a class=\"av-heading-link\" href=\"\/de\/product-categorie\/dw\/\" >DW<\/a><\/h2><div class='av-subheading av-subheading_below'><p>DeWalt, Stanley Fatmax, Black&amp;Decker<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc66yi4p-c629b9b64376194b0839ffb3850a86de\">\n#top .hr.hr-invisible.av-kc66yi4p-c629b9b64376194b0839ffb3850a86de{\nheight:38px;\n}\n<\/style>\n<div  class='hr av-kc66yi4p-c629b9b64376194b0839ffb3850a86de hr-invisible  avia-builder-el-30  el_after_av_heading  el_before_av_button '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap av-kc5uymfv-8d554396bc99cc3f1e81860a0f04bd5d-wrap avia-button-left  avia-builder-el-31  el_after_av_hr  el_before_av_iconlist '><a href='\/de\/product-categorie\/dw\/'  class='avia-button av-kc5uymfv-8d554396bc99cc3f1e81860a0f04bd5d av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-left avia-color-theme-color'  ><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >DW Aufnahme<\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a\">\n#top .avia-icon-list-container.av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a .iconlist_icon{\ncolor:#b02b2c;\n}\n<\/style>\n<div  class='avia-icon-list-container av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a  avia-builder-el-32  el_after_av_button  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a avia-iconlist-animate'>\n<li><a href='\/de\/product-categorie\/dw\/dw-hout\/' title='DW Holz'  class='iconlist_icon av-av_iconlist_item-81114e0122a67398af3067991679d590 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/dw\/dw-hout\/' title='DW Holz'>DW Holz<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/dw\/dw-hout-metaal\/' title='DW Holz\/Metall'  class='iconlist_icon av-av_iconlist_item-51e86c43617bfc76efc48cfe5dfa56bd avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/dw\/dw-hout-metaal\/' title='DW Holz\/Metall'>DW Holz\/Metall<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/dw\/dw-beton-steen\/' title='DW Beton\/Stein'  class='iconlist_icon av-av_iconlist_item-02d3d5b63e1c376b08ac3006eadbdd6a avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/dw\/dw-beton-steen\/' title='DW Beton\/Stein'>DW Beton\/Stein<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/dw\/dw-kit-lijm\/' title='DW Kitt\/Leim'  class='iconlist_icon av-av_iconlist_item-759378ba5eab329b95d7cb79c37e0bd8 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/dw\/dw-kit-lijm\/' title='DW Kitt\/Leim'>DW Kitt\/Leim<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/dw\/dw-schuren\/' title='DW Schleifen'  class='iconlist_icon av-av_iconlist_item-bd19b89dd746bb2ceb59ccdd233421fd avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/dw\/dw-schuren\/' title='DW Schleifen'>DW Schleifen<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/dw\/dw-sets\/' title='DW Sets'  class='iconlist_icon av-av_iconlist_item-d0a4abcbe612d1fefefbb59adbb2eae1 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/dw\/dw-sets\/' title='DW Sets'>DW Sets<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n<div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-phcysb-bc3893410f693fc9b6cf5d827cfabaa6\">\n.flex_column.av-phcysb-bc3893410f693fc9b6cf5d827cfabaa6{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\nbackground-color:#efefef;\n}\n<\/style>\n<div  class='flex_column av-phcysb-bc3893410f693fc9b6cf5d827cfabaa6 av_one_fourth  avia-builder-el-33  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_table_cell av-equal-height-column av-align-top avia-full-stretch  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc4h2yos-2d673c307f6cb77ddc0e27199fde6ea3\">\n.avia-image-container.av-kc4h2yos-2d673c307f6cb77ddc0e27199fde6ea3 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc4h2yos-2d673c307f6cb77ddc0e27199fde6ea3 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc4h2yos-2d673c307f6cb77ddc0e27199fde6ea3 av-styling- av-img-linked avia-align-left  avia-builder-el-34  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"\/de\/product-categorie\/un\/\" class='avia_image '  aria-label='MT_overview_UN'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-21672 avia-img-lazy-loading-not-21672 avia_image ' src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_UN.png\" alt='' title='MT_overview_UN'  height=\"350\" width=\"510\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_UN.png 510w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_UN-300x206.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_UN-450x309.png 450w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-d586314a12c19ce48c611f8b4d26f62b\">\n#top .av-special-heading.av-av_heading-d586314a12c19ce48c611f8b4d26f62b{\npadding-bottom:10px;\nfont-size:35px;\n}\nbody .av-special-heading.av-av_heading-d586314a12c19ce48c611f8b4d26f62b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-d586314a12c19ce48c611f8b4d26f62b .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-av_heading-d586314a12c19ce48c611f8b4d26f62b .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-d586314a12c19ce48c611f8b4d26f62b .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-d586314a12c19ce48c611f8b4d26f62b .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-d586314a12c19ce48c611f8b4d26f62b av-special-heading-h2 blockquote modern-quote  avia-builder-el-35  el_after_av_image  el_before_av_hr  av-inherit-size av-linked-heading'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  ><a class=\"av-heading-link\" href=\"\/de\/product-categorie\/un\/\" >UN<\/a><\/h2><div class='av-subheading av-subheading_below'><p>Bosch (&lt;2017), Milwaukee, Makita, Metabo, Hitachi\/Hikoki, AEG, Ryobi, Dremel, Skill, Einhell, Ferm<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc66yi4p-6096a1d47318291b5a5e6271d82982b2\">\n#top .hr.hr-invisible.av-kc66yi4p-6096a1d47318291b5a5e6271d82982b2{\nheight:18px;\n}\n<\/style>\n<div  class='hr av-kc66yi4p-6096a1d47318291b5a5e6271d82982b2 hr-invisible  avia-builder-el-36  el_after_av_heading  el_before_av_button '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap av-kc5uymfv-549ae6836e3a8321356071b353ac3cc5-wrap avia-button-left  avia-builder-el-37  el_after_av_hr  el_before_av_iconlist '><a href='\/de\/product-categorie\/un\/'  class='avia-button av-kc5uymfv-549ae6836e3a8321356071b353ac3cc5 av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-left avia-color-theme-color'  ><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >UN Aufnahme<\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a\">\n#top .avia-icon-list-container.av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a .iconlist_icon{\ncolor:#b02b2c;\n}\n<\/style>\n<div  class='avia-icon-list-container av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a  avia-builder-el-38  el_after_av_button  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a avia-iconlist-animate'>\n<li><a href='\/de\/product-categorie\/un\/un-hout\/' title='UN Holz'  class='iconlist_icon av-av_iconlist_item-3f4d4f6256d342ee580765b0107acecd avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/un\/un-hout\/' title='UN Holz'>UN Holz<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/un\/un-hout-metaal\/' title='UN Holz\/Metall'  class='iconlist_icon av-av_iconlist_item-aa56b59ca450f99250aaedd8279f9249 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/un\/un-hout-metaal\/' title='UN Holz\/Metall'>UN Holz\/Metall<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/un\/un-beton-steen\/' title='UN Beton\/Stein'  class='iconlist_icon av-av_iconlist_item-2fb372afaef76c08ad15b34443b0afbb avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/un\/un-beton-steen\/' title='UN Beton\/Stein'>UN Beton\/Stein<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/un\/un-kit-lijm\/' title='UN Kitt\/Leim'  class='iconlist_icon av-av_iconlist_item-19a06deb495ce08cec78a5d02d088fe5 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/un\/un-kit-lijm\/' title='UN Kitt\/Leim'>UN Kitt\/Leim<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/un\/un-schuren\/' title='UN Schleifen'  class='iconlist_icon av-av_iconlist_item-bed7463188a5c1019ea4a5f60d754508 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/un\/un-schuren\/' title='UN Schleifen'>UN Schleifen<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/un\/un-sets\/' title='UN Sets'  class='iconlist_icon av-av_iconlist_item-0e80a49077b7d6cdcb25c7774f6f0d01 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/un\/un-sets\/' title='UN Sets'>UN Sets<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n<div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-phcysb-3ff94ca8f5e095b9eab04eb721aa5342\">\n.flex_column.av-phcysb-3ff94ca8f5e095b9eab04eb721aa5342{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\nbackground-color:#efefef;\n}\n<\/style>\n<div  class='flex_column av-phcysb-3ff94ca8f5e095b9eab04eb721aa5342 av_one_fourth  avia-builder-el-39  el_after_av_one_fourth  el_before_av_hr  flex_column_table_cell av-equal-height-column av-align-top avia-full-stretch  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc4h2yos-1b2bab2992a7ca4a9bd5bcf15a91b412\">\n.avia-image-container.av-kc4h2yos-1b2bab2992a7ca4a9bd5bcf15a91b412 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kc4h2yos-1b2bab2992a7ca4a9bd5bcf15a91b412 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kc4h2yos-1b2bab2992a7ca4a9bd5bcf15a91b412 av-styling- av-img-linked avia-align-left  avia-builder-el-40  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"\/de\/product-categorie\/sc\/\" class='avia_image '  aria-label='MT_overview_SC'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-21664 avia-img-lazy-loading-not-21664 avia_image ' src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SC.png\" alt='' title='MT_overview_SC'  height=\"350\" width=\"510\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SC.png 510w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SC-300x206.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/12\/MT_overview_SC-450x309.png 450w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-6e9c53c4df2832fafbff63332935da25\">\n#top .av-special-heading.av-av_heading-6e9c53c4df2832fafbff63332935da25{\npadding-bottom:10px;\nfont-size:35px;\n}\nbody .av-special-heading.av-av_heading-6e9c53c4df2832fafbff63332935da25 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-6e9c53c4df2832fafbff63332935da25 .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-av_heading-6e9c53c4df2832fafbff63332935da25 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-6e9c53c4df2832fafbff63332935da25 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-6e9c53c4df2832fafbff63332935da25 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-6e9c53c4df2832fafbff63332935da25 av-special-heading-h2 blockquote modern-quote  avia-builder-el-41  el_after_av_image  el_before_av_hr  av-inherit-size av-linked-heading'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  ><a class=\"av-heading-link\" href=\"\/de\/product-categorie\/sc\/\" >SC<\/a><\/h2><div class='av-subheading av-subheading_below'><p>Fein SuperCut, Festool<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc66yi4p-63e95f7a7df595b611bcf454343fba07\">\n#top .hr.hr-invisible.av-kc66yi4p-63e95f7a7df595b611bcf454343fba07{\nheight:57px;\n}\n<\/style>\n<div  class='hr av-kc66yi4p-63e95f7a7df595b611bcf454343fba07 hr-invisible  avia-builder-el-42  el_after_av_heading  el_before_av_button '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap av-kc5uymfv-506d339068b656b554bb24ca544ed458-wrap avia-button-left  avia-builder-el-43  el_after_av_hr  el_before_av_iconlist '><a href='\/de\/product-categorie\/sc\/'  class='avia-button av-kc5uymfv-506d339068b656b554bb24ca544ed458 av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-left avia-color-theme-color'  ><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >SC Aufnahme<\/span><\/a><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a\">\n#top .avia-icon-list-container.av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a .iconlist_icon{\ncolor:#b02b2c;\n}\n<\/style>\n<div  class='avia-icon-list-container av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a  avia-builder-el-44  el_after_av_button  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-kc5v68k0-ab9287a4f81f611021e5d58f2a75d68a avia-iconlist-animate'>\n<li><a href='\/de\/product-categorie\/sc\/sc-hout\/' title='SC Holz'  class='iconlist_icon av-av_iconlist_item-3a8f027d4ec851b76b5da506cee0ce3f avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sc\/sc-hout\/' title='SC Holz'>SC Holz<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sc\/sc-hout-metaal\/' title='SC Holz\/Metall'  class='iconlist_icon av-av_iconlist_item-d1585d3a2f2ac516faa7e12eb93d0338 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sc\/sc-hout-metaal\/' title='SC Holz\/Metall'>SC Holz\/Metall<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sc\/sc-beton-steen\/' title='SC Beton\/Stein'  class='iconlist_icon av-av_iconlist_item-7f27d835a644ad381b1296a78b12fd97 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sc\/sc-beton-steen\/' title='SC Beton\/Stein'>SC Beton\/Stein<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sc\/sc-kit-lijm\/' title='SC Kitt\/Leim'  class='iconlist_icon av-av_iconlist_item-354a07b921116af5b3faae89ae7ab86b avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sc\/sc-kit-lijm\/' title='SC Kitt\/Leim'>SC Kitt\/Leim<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sc\/sc-schuren\/' title='SC Schleifen'  class='iconlist_icon av-av_iconlist_item-bfa323cb74e43c2d907cbacae620e4a4 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sc\/sc-schuren\/' title='SC Schleifen'>SC Schleifen<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='\/de\/product-categorie\/sc\/sc-sets\/' title='SC Sets'  class='iconlist_icon av-av_iconlist_item-569dbe8ca89bf274cb08ec85f036dc3f avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue875' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href='\/de\/product-categorie\/sc\/sc-sets\/' title='SC Sets'>SC Sets<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kc5wyy0u-8b8a5fc8bc28fd0473b41cf4d02991bf\">\n#top .hr.hr-invisible.av-kc5wyy0u-8b8a5fc8bc28fd0473b41cf4d02991bf{\nheight:80px;\n}\n<\/style>\n<div  class='hr av-kc5wyy0u-8b8a5fc8bc28fd0473b41cf4d02991bf hr-invisible  avia-builder-el-45  el_after_av_one_fourth  el_before_av_section  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mix6togj-450bca830c77107c39851a0a05a2f7c2\">\n.avia-section.av-mix6togj-450bca830c77107c39851a0a05a2f7c2{\nbackground-color:#e30615;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-mix6togj-450bca830c77107c39851a0a05a2f7c2 alternate_color avia-section-default avia-no-border-styling  avia-builder-el-46  el_after_av_hr  avia-builder-el-last  avia-bg-style-parallax container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5143'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mhuego6l-e671c238d6e264bed2546611916bb799\">\n#top .av_textblock_section.av-mhuego6l-e671c238d6e264bed2546611916bb799 .avia_textblock{\ncolor:#ffffff;\n}\n<\/style>\n<section  class='av_textblock_section av-mhuego6l-e671c238d6e264bed2546611916bb799 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Haben Sie eine Frage?<\/h2>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-43639eb3b16efaf187ad06602748df50\">\n#top .flex_column.av-av_one_fifth-43639eb3b16efaf187ad06602748df50{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-av_one_fifth-43639eb3b16efaf187ad06602748df50{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-av_one_fifth-43639eb3b16efaf187ad06602748df50{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-43639eb3b16efaf187ad06602748df50 av_one_fifth  avia-builder-el-48  el_after_av_textblock  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b\">\n#top .flex_column.av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-f8baaa70fc9c1960a2a9eb4680f8042b av_three_fifth  avia-builder-el-49  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><div  class='avia-button-wrap av-mhueh9mu-9676db2681e79e503eb06c8e69d5a8cb-wrap avia-button-center  avia-builder-el-50  avia-builder-el-no-sibling '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mhueh9mu-9676db2681e79e503eb06c8e69d5a8cb\">\n#top #wrap_all .avia-button.av-mhueh9mu-9676db2681e79e503eb06c8e69d5a8cb{\nbackground-color:#ffffff;\nborder-color:#ffffff;\ncolor:#e30615;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='\/de\/contact'  class='avia-button av-mhueh9mu-9676db2681e79e503eb06c8e69d5a8cb av-link-btn avia-icon_select-yes-left-icon avia-size-x-large avia-position-center'  ><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue83c' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Stellen Sie Ihre Frage direkt den Qblades-Experten<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-49f6e875884219cf77c24341e550af53\">\n#top .flex_column.av-av_one_fifth-49f6e875884219cf77c24341e550af53{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-av_one_fifth-49f6e875884219cf77c24341e550af53{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-av_one_fifth-49f6e875884219cf77c24341e550af53{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-49f6e875884219cf77c24341e550af53 av_one_fifth  avia-builder-el-51  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>This is a Page excerpt. It will be displayed for search results<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-5143","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter - Qblades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qblades.nl\/de\/homepage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter - Qblades\" \/>\n<meta property=\"og:description\" content=\"This is a Page excerpt. It will be displayed for search results\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qblades.nl\/de\/homepage\/\" \/>\n<meta property=\"og:site_name\" content=\"Qblades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/qbladescom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T06:47:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/\",\"url\":\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/\",\"name\":\"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter - Qblades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\"},\"datePublished\":\"2015-08-27T08:05:37+00:00\",\"dateModified\":\"2026-05-12T06:47:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"name\":\"Qblades\",\"description\":\"importeur en distributeur van Multitool zaagbladen en accessoires\",\"publisher\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qblades.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\",\"name\":\"Qblades\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"contentUrl\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"width\":2840,\"height\":1420,\"caption\":\"Qblades\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/qbladescom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/qblades\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter - Qblades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qblades.nl\/de\/homepage\/","og_locale":"de_DE","og_type":"article","og_title":"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter - Qblades","og_description":"This is a Page excerpt. It will be displayed for search results","og_url":"https:\/\/qblades.nl\/de\/homepage\/","og_site_name":"Qblades","article_publisher":"https:\/\/www.facebook.com\/qbladescom\/","article_modified_time":"2026-05-12T06:47:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/qblades.nl\/de\/homepage\/","url":"https:\/\/qblades.nl\/de\/homepage\/","name":"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter - Qblades","isPartOf":{"@id":"https:\/\/qblades.nl\/#website"},"datePublished":"2015-08-27T08:05:37+00:00","dateModified":"2026-05-12T06:47:52+00:00","breadcrumb":{"@id":"https:\/\/qblades.nl\/de\/homepage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qblades.nl\/de\/homepage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/qblades.nl\/de\/homepage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qblades.nl\/de\/homepage\/"},{"@type":"ListItem","position":2,"name":"Multitools\u00e4gebl\u00e4tter, S\u00e4bels\u00e4gebl\u00e4tter und Stichs\u00e4gebl\u00e4tter"}]},{"@type":"WebSite","@id":"https:\/\/qblades.nl\/#website","url":"https:\/\/qblades.nl\/","name":"Qblades","description":"importeur en distributeur van Multitool zaagbladen en accessoires","publisher":{"@id":"https:\/\/qblades.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qblades.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/qblades.nl\/#organization","name":"Qblades","url":"https:\/\/qblades.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/","url":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","contentUrl":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","width":2840,"height":1420,"caption":"Qblades"},"image":{"@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/qbladescom\/","https:\/\/www.linkedin.com\/company\/qblades"]}]}},"_links":{"self":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/pages\/5143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/comments?post=5143"}],"version-history":[{"count":76,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/pages\/5143\/revisions"}],"predecessor-version":[{"id":23393,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/pages\/5143\/revisions\/23393"}],"wp:attachment":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/media?parent=5143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}