{"id":16938,"date":"2024-03-25T14:12:28","date_gmt":"2024-03-25T13:12:28","guid":{"rendered":"https:\/\/qblades.nl\/?post_type=product&#038;p=16938"},"modified":"2026-03-19T14:33:25","modified_gmt":"2026-03-19T13:33:25","slug":"qrc0308-reciprozaagblad","status":"publish","type":"product","link":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/","title":{"rendered":"QRC0308 &#8211; S\u00e4bels\u00e4geblatt &#8211;  203mm TPI: 6\/10"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-q64l19-30b51361b9828d3e24abdb747ebe908d\">\n.flex_column.av-q64l19-30b51361b9828d3e24abdb747ebe908d{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-q64l19-30b51361b9828d3e24abdb747ebe908d av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-kbt2kwvb-647f5b2ff18d2e1a6a7e25d2225d2614 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>QRC0308 &#8211; S\u00e4bels\u00e4geblatt<\/h1>\n<\/div><\/section><br \/>\n<div  class='tabcontainer av-kbt1fdtt-570302c26c136ee73934f54c4eaf7250 top_tab  avia-builder-el-2  el_after_av_textblock  el_before_av_hr ' role='tablist'>\n<section class='av_tab_section av_tab_section av-okm7op-89dd4f94abe76221445fff8664685058'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab active_tab' role='tab' tabindex='0' data-fake-id='#tab-id-1' aria-controls='tab-id-1-content'  itemprop=\"headline\" >Beschreibung<\/div><div id='tab-id-1-content' class='tab_content active_tab_content' aria-hidden=\"false\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><p><span data-sheets-root=\"1\">Ideal f\u00fcr schnelle und gerade Schnitte.<\/span><\/p>\n<p><em>Holz, Konstruktionsholz, Kunststoffe, Gipskarton.<\/em><\/p>\n<p>Material: HCS<br \/>\nVerzahnung: 6\/10tpi<br \/>\nL\u00e4nge: 203mm \/ 8&#8243;<br \/>\nDicke: 1,3mm<\/p>\n<p>Zu verwenden als: Bosch S2345X<\/p>\n<p><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-12767 alignleft\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-hout.png 500w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><\/a><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-12780\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-pvc.png 500w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-20963 size-thumbnail\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/10\/TPI-QRC0308-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2025\/10\/TPI-QRC0308-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/10\/TPI-QRC0308-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/10\/TPI-QRC0308-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/10\/TPI-QRC0308-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2025\/10\/TPI-QRC0308-100x100.png 100w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><\/p>\n<\/div><\/div><\/section>\n<section class='av_tab_section av_tab_section av-jp5o0t-ed7407fd516298d66a34e3610def0c64'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab' role='tab' tabindex='0' data-fake-id='#tab-id-2' aria-controls='tab-id-2-content'  itemprop=\"headline\" >Dealers<\/div><div id='tab-id-2-content' class='tab_content' aria-hidden=\"true\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><p><a href=\"\/dealer-popup\/?iframe=true&amp;width=100%&amp;height=100%\" rel=\"lightbox\">H\u00e4ndler anzeigen und finden<\/a><\/p>\n<\/div><\/div><\/section>\n<\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e\">\n#top .hr.hr-invisible.av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e hr-invisible  avia-builder-el-3  el_after_av_tab_container  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kbt7ed44-0c3712b76d2b77f294d6162484d6513c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h5>Verf\u00fcgbar in:<\/h5>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e\">\n#top .hr.hr-invisible.av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e hr-invisible  avia-builder-el-5  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kbt2kwvb-647f5b2ff18d2e1a6a7e25d2225d2614 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><table class=\"productcodes\">\n<tbody>\n<tr>\n<td>5ST<\/td>\n<td>EAN: 8718627385067<br \/>\nQBL385067<\/td>\n<\/tr>\n<tr>\n<td>50ST<\/td>\n<td>EAN: 8718627385753<br \/>\nQBL385753<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc\">\n.flex_column.av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc av_one_half  avia-builder-el-7  el_after_av_one_half  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ltzmtcut-e32911542528524e66c29264f9fad0d3\">\n#top .avia-gallery.av-ltzmtcut-e32911542528524e66c29264f9fad0d3 .avia-gallery-thumb a{\nwidth:50%;\n}\n<\/style>\n<div  class='avia-gallery av-ltzmtcut-e32911542528524e66c29264f9fad0d3 avia_animate_when_visible  avia-builder-el-8  avia-builder-el-no-sibling  animations_off av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/\"><a class='avia-gallery-big fakeLightbox avianolink noLightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-onclick='1' title='QRC0308' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-16948 avia-img-lazy-loading-not-16948\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png\" title='QRC0308' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-100x100.png 100w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/span><\/a><div class='avia-gallery-thumb'><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png' class='first_thumb avianolink noLightbox ' data-onclick='1' title='QRC0308'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-16948 avia-img-lazy-loading-not-16948\"   src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-300x300.png\" width=\"300\" height=\"300\"  title='QRC0308' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16948 avia-img-lazy-loading-16948\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png\" title='QRC0308' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><\/a><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs.png' class='avianolink noLightbox ' data-onclick='2' title='QRC0308-5pcs'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-16944 avia-img-lazy-loading-not-16944\"   src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-300x300.png\" width=\"300\" height=\"300\"  title='QRC0308-5pcs' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16944 avia-img-lazy-loading-16944\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs.png\" title='QRC0308-5pcs' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308-5pcs-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><\/a><\/div><\/div><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b\">\n#top .hr.hr-invisible.av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b{\nheight:100px;\n}\n<\/style>\n<div  class='hr av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b hr-invisible  avia-builder-el-9  el_after_av_one_half  el_before_av_product_upsells '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  class='av-woo-product-related-upsells av-lceapp-35f469ec0610a8cd6d78c6217f9b09c1  avia-builder-el-10  el_after_av_hr  avia-builder-el-last '><div class='product_column product_column_4'>\n\t<section class=\"related products\">\n\n\t\t\t\t\t<h2>\u00c4hnliche Produkte<\/h2>\n\t\t\t\t<ul class=\"products columns-4\">\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17011 status-publish first instock product_cat-recipro-hout-met-spijkers-de product_cat-recipro-de has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/de\/product\/qrc1112-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-450x450.png\" class=\"wp-image-17021 avia-img-lazy-loading-17021 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1112 &#8211; S\u00e4bels\u00e4geblatt &#8211; 300MM TPI: 5\/8<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-16838 status-publish instock product_cat-recipro-hout-de product_cat-recipro-de has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/de\/product\/qrc0109-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-450x450.png\" class=\"wp-image-16896 avia-img-lazy-loading-16896 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-2048x2048.png 2048w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-100x100.png 100w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC0109 &#8211; S\u00e4bels\u00e4geblatt &#8211; 240mm TPI: 5<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17048 status-publish instock product_cat-recipro-hout-met-spijkers-de product_cat-recipro-de has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/de\/product\/qrc1312-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png\" class=\"wp-image-17058 avia-img-lazy-loading-17058 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1312 &#8211; S\u00e4bels\u00e4geblatt &#8211; 302mm TPI: 6<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17106 status-publish last instock product_cat-recipro-alleskunners-de product_cat-recipro-de has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/de\/product\/qrc2508-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png\" class=\"wp-image-17116 avia-img-lazy-loading-17116 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC2508 &#8211; S\u00e4bels\u00e4geblatt &#8211; 203mm TPI: 6\/10<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t<\/ul>\n\n\t<\/section>\n\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":16948,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1859,1841],"product_tag":[],"class_list":{"0":"post-16938","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-recipro-hout-de","7":"product_cat-recipro-de","8":"pa_merk-black-decker","9":"pa_merk-dewalt-de","10":"pa_merk-parkside-de","11":"pa_merk-stanley-de","13":"first","14":"instock","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QRC0308 - S\u00e4bels\u00e4geblatt - 203mm TPI: 6\/10 - Qblades<\/title>\n<meta name=\"description\" content=\"De qrc0308 zorgt voor moeiteloze precisie bij het zagen van zowel dunne als dikke (hout)materialen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QRC0308 - S\u00e4bels\u00e4geblatt - 203mm TPI: 6\/10 - Qblades\" \/>\n<meta property=\"og:description\" content=\"De qrc0308 zorgt voor moeiteloze precisie bij het zagen van zowel dunne als dikke (hout)materialen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/\" \/>\n<meta property=\"og:site_name\" content=\"Qblades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/qbladescom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T13:33:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/\",\"url\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/\",\"name\":\"QRC0308 - S\u00e4bels\u00e4geblatt - 203mm TPI: 6\\\/10 - Qblades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QRC0308.png\",\"datePublished\":\"2024-03-25T13:12:28+00:00\",\"dateModified\":\"2026-03-19T13:33:25+00:00\",\"description\":\"De qrc0308 zorgt voor moeiteloze precisie bij het zagen van zowel dunne als dikke (hout)materialen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QRC0308.png\",\"contentUrl\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QRC0308.png\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/de\\\/product\\\/qrc0308-reciprozaagblad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qblades.nl\\\/de\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/qblades.nl\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"QRC0308 &#8211; S\u00e4bels\u00e4geblatt &#8211; 203mm TPI: 6\\\/10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"name\":\"Qblades\",\"description\":\"importeur en distributeur van Multitool zaagbladen en accessoires\",\"publisher\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qblades.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\",\"name\":\"Qblades\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"contentUrl\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"width\":2840,\"height\":1420,\"caption\":\"Qblades\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/qbladescom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/qblades\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QRC0308 - S\u00e4bels\u00e4geblatt - 203mm TPI: 6\/10 - Qblades","description":"De qrc0308 zorgt voor moeiteloze precisie bij het zagen van zowel dunne als dikke (hout)materialen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/","og_locale":"de_DE","og_type":"article","og_title":"QRC0308 - S\u00e4bels\u00e4geblatt - 203mm TPI: 6\/10 - Qblades","og_description":"De qrc0308 zorgt voor moeiteloze precisie bij het zagen van zowel dunne als dikke (hout)materialen.","og_url":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/","og_site_name":"Qblades","article_publisher":"https:\/\/www.facebook.com\/qbladescom\/","article_modified_time":"2026-03-19T13:33:25+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/","url":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/","name":"QRC0308 - S\u00e4bels\u00e4geblatt - 203mm TPI: 6\/10 - Qblades","isPartOf":{"@id":"https:\/\/qblades.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/#primaryimage"},"image":{"@id":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/#primaryimage"},"thumbnailUrl":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png","datePublished":"2024-03-25T13:12:28+00:00","dateModified":"2026-03-19T13:33:25+00:00","description":"De qrc0308 zorgt voor moeiteloze precisie bij het zagen van zowel dunne als dikke (hout)materialen.","breadcrumb":{"@id":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/#primaryimage","url":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png","contentUrl":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0308.png","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/qblades.nl\/de\/product\/qrc0308-reciprozaagblad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qblades.nl\/de\/homepage\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/qblades.nl\/products\/"},{"@type":"ListItem","position":3,"name":"QRC0308 &#8211; S\u00e4bels\u00e4geblatt &#8211; 203mm TPI: 6\/10"}]},{"@type":"WebSite","@id":"https:\/\/qblades.nl\/#website","url":"https:\/\/qblades.nl\/","name":"Qblades","description":"importeur en distributeur van Multitool zaagbladen en accessoires","publisher":{"@id":"https:\/\/qblades.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qblades.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/qblades.nl\/#organization","name":"Qblades","url":"https:\/\/qblades.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/","url":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","contentUrl":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","width":2840,"height":1420,"caption":"Qblades"},"image":{"@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/qbladescom\/","https:\/\/www.linkedin.com\/company\/qblades"]}]}},"_links":{"self":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/product\/16938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/media\/16948"}],"wp:attachment":[{"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/media?parent=16938"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/product_brand?post=16938"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/product_cat?post=16938"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/qblades.nl\/de\/wp-json\/wp\/v2\/product_tag?post=16938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}