{"id":4776,"date":"2015-05-01T09:50:10","date_gmt":"2015-05-01T07:50:10","guid":{"rendered":"http:\/\/qblades.nl\/assortiment-metaal\/?lang=en"},"modified":"2020-03-04T13:51:06","modified_gmt":"2020-03-04T12:51:06","slug":"assortiment-metaal","status":"publish","type":"page","link":"https:\/\/qblades.nl\/en\/assortiment-metaal\/","title":{"rendered":"Assortment &#8211; WOOD-METAL"},"content":{"rendered":"<div id='layer_slider_1'  class='avia-layerslider main_color avia-shadow  avia-builder-el-0  el_before_av_productgrid  avia-builder-el-first  container_wrap fullsize'  style='height: 151px;'  ><\/div><div id='after_layer_slider_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4776'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-product-slider-container av-33epmz-fe36587850454815ea7dc92517897a87 template-shop avia-content-slider avia-content-grid-active shop_columns_5  avia-builder-el-1  el_after_av_layerslider  avia-builder-el-no-sibling  avia-content-slider-odd  avia-builder-el-1  el_after_av_layerslider  avia-builder-el-no-sibling  av-slideshow-ui av-slider-hover-pause av-slideshow-manual av-loop-once av-loop-manual-endless avia-product-slider1' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:true,&quot;show_slide_delay&quot;:0}\"><div class='avia-content-slider-inner'><ul class=\"products\"><li class=\"product type-product post-6983 status-publish first instock product_cat-hout-metaal-en product_cat-sets-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-en product_cat-sl-slm-hout-metaal-en product_cat-sl-slm-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl92-set-hout-metaal-standaard\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-450x450.png\" class=\"wp-image-13805 avia-img-lazy-loading-13805 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SL92\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL92.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL92 SET Wood-Metal Standard<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-4886 status-publish instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-en product_cat-sc-hout-metaal-en product_cat-sc-sets-en product_cat-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc92-set\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-450x450.jpg\" class=\"wp-image-15473 avia-img-lazy-loading-15473 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-450x450.jpg 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-300x300.jpg 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-1030x1030.jpg 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-80x80.jpg 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-768x768.jpg 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-36x36.jpg 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-180x180.jpg 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-705x705.jpg 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92-100x100.jpg 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/Set-SC92.jpg 1200w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC92 SET Wood-Metal Standard<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-4093 status-publish instock product_cat-hout-metaal-en product_cat-sets-en product_cat-un-en product_cat-un-hout product_cat-un-hout-metaal-en product_cat-un-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un92-set-hout-metaal\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-450x450.png\" class=\"wp-image-16368 avia-img-lazy-loading-16368 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN92.png 1772w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN92 SET Wood-Metal Standard<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12598 status-publish instock product_cat-hout-metaal-en product_cat-kit-lijm-en product_cat-sc-en product_cat-sc-beton-steen-en product_cat-sc-hout-en product_cat-sc-hout-metaal-en product_cat-sc-kit-lijm-en product_cat-sc-sets-en product_cat-sets-en product_cat-steen-beton-en product_cat-wood product_tag-alle-toepassingen-en product_tag-compleet-en product_tag-multi-functioneel-en product_tag-sc91-en product_tag-set-en product_tag-supercut-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc91-set-assorti-totaal\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-450x450.png\" class=\"wp-image-15468 avia-img-lazy-loading-15468 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/SC91.png 1370w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC91 SET Assortment COMPLETE<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12596 status-publish last instock product_cat-hout-metaal-en product_cat-kit-lijm-en product_cat-sets-en product_cat-steen-beton-en product_cat-un-en product_cat-un-beton-steen-en product_cat-un-hout product_cat-un-hout-metaal-en product_cat-un-kit-lijm-en product_cat-un-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un91-set-assorti-totaal\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-450x450.png\" class=\"wp-image-16400 avia-img-lazy-loading-16400 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2014\/01\/UN91-4.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN91 SET Assortment COMPLETE<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5054 status-publish first instock product_cat-hout-metaal-en product_cat-sc-hout-en product_cat-sc-hout-metaal-en product_cat-sc-sets-en product_cat-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc90-set-hout-metaal-compleet\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC90-450x450.png\" class=\"wp-image-13695 avia-img-lazy-loading-13695 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC90\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC90-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC90-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC90-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC90-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC90-100x100.png 100w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC90 SET Wood-Metal Complete<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5050 status-publish instock product_cat-hout-metaal-en product_cat-sets-en product_cat-un-en product_cat-un-hout product_cat-un-hout-metaal-en product_cat-un-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un90-set-hout-metaal-compleet\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN90-450x450.png\" class=\"wp-image-14000 avia-img-lazy-loading-14000 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN90\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN90-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN90-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN90-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN90-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN90-100x100.png 100w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN90 SET Wood-Metal Complete<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12105 status-publish instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-carbide-en product_tag-ferro-metaal-en product_tag-metaal-en product_tag-pro-en product_tag-rvs-en product_tag-sl-en product_tag-staal-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-tin-coating-en product_tag-verharde-schroeven-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl81-zaagblad-carbide-pro-35x45mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-450x450.png\" class=\"wp-image-13800 avia-img-lazy-loading-13800 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SL81\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL81.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL81 Saw blade Carbide-Pro 35x45mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5138 status-publish instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-80mm-en product_tag-hout-en product_tag-metaal-en product_tag-sc21-en product_tag-segment-en product_tag-supercut-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc21-zaagblad-hss-80mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-450x450.png\" class=\"wp-image-13615 avia-img-lazy-loading-13615 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC21\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC21.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC21 Saw blade HSS 80mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-4910 status-publish last instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-80mm-en product_tag-hout-en product_tag-hss-en product_tag-metaal-en product_tag-segment-en product_tag-un21-en product_tag-universal has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un21-zaagblad-hss-80mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-450x450.png\" class=\"wp-image-13915 avia-img-lazy-loading-13915 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN21\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN21.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN21 Saw blade HSS 80mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12097 status-publish first instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-85mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-segment-en product_tag-sl20-en product_tag-starlock-en product_tag-starlock-plus-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl20-segmentzaagblad-bi-metaal-85mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-450x450.png\" class=\"wp-image-13760 avia-img-lazy-loading-13760 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SL20\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL20.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL20 Segment saw blade 85mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5070 status-publish instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-88mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-sc20-en product_tag-segment-en product_tag-supercut-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc20-segment-zaagblad-bi-metaal-88mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-450x450.png\" class=\"wp-image-13610 avia-img-lazy-loading-13610 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC20\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC20.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC20 Segment saw blade Bi-Metal 88mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5074 status-publish instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-88mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-segment-en product_tag-un20-en product_tag-universal product_tag-zaagbald-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un20-segment-zaagblad-bi-metaal-88mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-450x450.png\" class=\"wp-image-13910 avia-img-lazy-loading-13910 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN20\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN20.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN20 Segment saw blade 88mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12175 status-publish instock product_cat-hout-metaal-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_cat-slm-en product_tag-32mm-en product_tag-78mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-slm17-en product_tag-starlock-max-en product_tag-verlengd-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/slm17-zaagblad-bi-metaal-32x78mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-450x450.png\" class=\"wp-image-13830 avia-img-lazy-loading-13830 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SLM17\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM17.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SLM17 Zaagblad Bi-Metaal 32x78mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-6901 status-publish last instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-28mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sl-en product_tag-sl15-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl15-zaagblad-bi-metaal-28x55mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-450x450.png\" class=\"wp-image-15250 avia-img-lazy-loading-15250 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2016\/12\/QBLADES-SL15.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL15 Saw blade Bi-metal 28x55mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-11998 status-publish first instock product_cat-dw product_cat-dw-hout-metaal-en-2 product_cat-hout-metaal-en product_tag-28mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-dewalt-en product_tag-dw15-en product_tag-hout-en product_tag-metaal-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/dw15-zaagblad-bi-metaal-28x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-450x450.png\" class=\"wp-image-13505 avia-img-lazy-loading-13505 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-DW15\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW15.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DW15 Saw blade Bi-metal 28x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5066 status-publish instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-28mm-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-sc15-en product_tag-supercut-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc15-zaagblad-bi-metaal-28x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-450x450.png\" class=\"wp-image-13605 avia-img-lazy-loading-13605 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC15\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC15.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC15 Saw blade Bi-metal 28x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5062 status-publish instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-28mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-un15-en product_tag-universal product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un15-zaagblad-bi-metaal-28x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-450x450.png\" class=\"wp-image-13905 avia-img-lazy-loading-13905 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN15\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN15.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN15 Saw blade Bi-metal 28x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-7287 status-publish instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-65x40mm-en product_tag-bi-metaal-en product_tag-breed-en product_tag-hout-en product_tag-metaal-en product_tag-metal-en product_tag-qblades-en product_tag-sl13-en product_tag-starlock-en product_tag-wood-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl13-zaagblad-bi-metaal-65x50mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-450x450.png\" class=\"wp-image-13750 avia-img-lazy-loading-13750 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SL13\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL13.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL13 Saw blade Bi-metal 65x50mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-11993 status-publish last instock product_cat-dw product_cat-dw-hout-metaal-en-2 product_cat-hout-metaal-en product_tag-68mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-breed-en product_tag-dewalt-en product_tag-dw13-en product_tag-hout-en product_tag-metaal-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/dw13-zaagblad-bi-metaal-68x42mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-450x450.png\" class=\"wp-image-13500 avia-img-lazy-loading-13500 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-DW13\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW13.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DW13 Saw blade Bi-metal 68x42mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-7354 status-publish first instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-68mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-breed-en product_tag-hout-en product_tag-metaal-en product_tag-sc13-en product_tag-supercut-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sc13-zaagblad-bi-metaal-68x42mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-450x450.png\" class=\"wp-image-13600 avia-img-lazy-loading-13600 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC13\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC13.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC13 Saw blade Bi-metal 68x42mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-7145 status-publish instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-68mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-breed-en product_tag-hout-en product_tag-metaal-en product_tag-un13-en product_tag-universal product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/un13-zaagblad-bi-metaal-68x42mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-450x450.png\" class=\"wp-image-13900 avia-img-lazy-loading-13900 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN13\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN13.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN13 Saw blade Bi-metal 68x42mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12169 status-publish instock product_cat-hout-metaal-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_cat-slm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-slm12-en product_tag-starlock-max-en product_tag-verlengd-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/slm12-zaagblad-bi-metaal-42x78mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-450x450.png\" class=\"wp-image-13825 avia-img-lazy-loading-13825 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SLM12\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SLM12.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SLM12 Saw blade bi-metal 42x78mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5391 status-publish instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-78mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sc12-en product_tag-supercut-en product_tag-verlengd-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc12-zaagblad-bi-metaal-44x78mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-450x450.png\" class=\"wp-image-13595 avia-img-lazy-loading-13595 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC12\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC12.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC12 Saw blade Bi-metal 44x78mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5381 status-publish last instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-78mm-en product_tag-bi-metaal-en product_tag-bi-metal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-un12-en product_tag-verlengd-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un12-zaagblad-bi-metaal-44x78mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-450x450.png\" class=\"wp-image-13895 avia-img-lazy-loading-13895 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN12\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN12.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN12 Saw blade Bi-metal 44x78mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-6311 status-publish first instock product_cat-dw product_cat-dw-hout-metaal-en-2 product_cat-hout-metaal-en product_tag-45mm-en product_tag-allround-en product_tag-bi-metaal-en product_tag-bim-en product_tag-dewalt-en product_tag-dw11-en product_tag-hout-en product_tag-metaal-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/dw11-zaagblad-bi-metaal-45x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-450x450.png\" class=\"wp-image-13495 avia-img-lazy-loading-13495 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-DW11\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW11.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DW11 Saw blade Bi-metal 45x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-4998 status-publish instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-45mm-en product_tag-allround-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-sc11-en product_tag-supercut-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc11-zaagblad-bi-metaal-45x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-450x450.png\" class=\"wp-image-13590 avia-img-lazy-loading-13590 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC11\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC11.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC11 Saw blade Bi-metal 45x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-4930 status-publish instock product_cat-bestseller-en product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-45mm-en product_tag-allround-en product_tag-bi-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-un11-en product_tag-universal product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un11-zaagblad-bi-metaal-45x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-450x450.png\" class=\"wp-image-13890 avia-img-lazy-loading-13890 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN11\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN11.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN11 Saw blade Bi-metal 45x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-7359 status-publish instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-allround-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sl-en product_tag-sl10-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl10-zaagblad-bi-metaal-44x55mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-450x450.png\" class=\"wp-image-13745 avia-img-lazy-loading-13745 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SL10\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL10.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL10 Saw blade Bi-metal 44x55mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-12036 status-publish last instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-20mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sl-en product_tag-sl07-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl07-zaagblad-bi-metaal-20x50mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-450x450.png\" class=\"wp-image-13730 avia-img-lazy-loading-13730 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SL07\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SL07.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL07 Saw blade Bi-metal 20x40mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5006 status-publish first instock product_cat-hout-metaal-en product_cat-sc-en product_cat-sc-hout-metaal-en product_tag-34mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sc03-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sc03-zaagblad-bi-metaal-34x40mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-450x450.png\" class=\"wp-image-13560 avia-img-lazy-loading-13560 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-SC03\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-SC03.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SC03 Saw blade Bi-metal 34x40mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-5082 status-publish instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-bim-en product_tag-hout-en product_tag-metaal-en product_tag-un03-en product_tag-universal product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-un03-zaagblad-bi-metaal-34x40mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-450x450.png\" class=\"wp-image-13860 avia-img-lazy-loading-13860 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-UN03\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-UN03.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN03 Saw blade Bi-metal 34x40mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-14057 status-publish instock product_cat-dw product_cat-dw-hout-metaal-en-2 product_cat-hout-metaal-en product_tag-88mm-en product_tag-bi-metaal-en product_tag-bim-en product_tag-segment-en product_tag-universal product_tag-zaagbald-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/dw20-segment-saw-blade-88mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-450x450.png\" class=\"wp-image-13510 avia-img-lazy-loading-13510 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"QBLADES-DW20\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/09\/QBLADES-DW20.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DW20 Segment saw blade 88mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-14952 status-publish instock product_cat-hout-metaal-en product_cat-un-en product_cat-un-hout-metaal-en product_tag-carbide-en product_tag-ferro-metaal-en product_tag-metaal-en product_tag-pro-en product_tag-rvs-en product_tag-staal-en product_tag-tin-coating-en product_tag-un product_tag-verharde-schroeven-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/un82-zaagblad-carbide-pro-35x40mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-450x450.png\" class=\"wp-image-15384 avia-img-lazy-loading-15384 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2021\/09\/un82-01-2022.png 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">UN82 Sawblade Carbide-PRO 35x40mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-15135 status-publish last instock product_cat-dw product_cat-dw-hout-metaal-en-2 product_cat-hout-metaal-en product_tag-carbide-en product_tag-dw product_tag-ferro-metaal-en product_tag-metaal-en product_tag-pro-en product_tag-rvs-en product_tag-staal-en product_tag-tin-coating-en product_tag-verharde-schroeven-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/dw82-zaagblad-carbide-pro-35x40mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-450x450.png\" class=\"wp-image-16380 avia-img-lazy-loading-16380 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/DW82-P.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">DW82 Sawblade Carbide-PRO 35x40mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-15195 status-publish first instock product_cat-hout-metaal-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_cat-slp product_tag-bim-en product_tag-breed-en product_tag-slp11 product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/slp11-zaagblad-bi-metaal-44x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-450x450.png\" class=\"wp-image-15199 avia-img-lazy-loading-15199 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP11.png 886w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SLP11 Sawblade Bi-Metal 44x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-15205 status-publish instock product_cat-hout-metaal-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_cat-slp product_tag-bim-en product_tag-breed-en product_tag-slp15 product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/slp15-zaagblad-bi-metaal-28x60mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-450x450.png\" class=\"wp-image-15209 avia-img-lazy-loading-15209 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2022\/01\/QBLADES-SLP15.png 886w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SLP15 Sawblade Bi-Metal 28x60mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-16524 status-publish instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-20mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sl-en product_tag-sl07-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/qblades-sl03-zaagblad-bi-metaal-35x50mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-450x450.png\" class=\"wp-image-16457 avia-img-lazy-loading-16457 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"sl0\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2023\/10\/QBLADES-SL03.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL03 Saw blade Bi-metal 35x50mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-23318 status-publish instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-20mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sl-en product_tag-sl07-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl01-zaagblad-bi-metaal-10x30mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-450x450.png\" class=\"wp-image-23334 avia-img-lazy-loading-23334 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL01.png 1500w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL01 Saw blade Bi-metal 10x30mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-23351 status-publish last instock product_cat-hout-metaal-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_tag-20mm-en product_tag-bi-metaal-en product_tag-hout-en product_tag-metaal-en product_tag-sl-en product_tag-sl07-en product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl14-zaagblad-bi-metaal-30x50mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-450x450.png\" class=\"wp-image-23433 avia-img-lazy-loading-23433 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SL14-002-v3.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL14 Saw blade Bi-metal 30x50mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-23366 status-publish first instock product_cat-hout-metaal-en product_cat-sl-slm-en product_cat-sl-slm-hout-metaal-en product_cat-slp product_tag-bim-en product_tag-breed-en product_tag-slp11 product_tag-starlock-en product_tag-starlock-plus-en product_tag-zaagblad-en has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/slp13-zaagblad-bimetaal-65x50mm\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-450x450.png\" class=\"wp-image-23346 avia-img-lazy-loading-23346 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/05\/SLP13.png 1500w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SLP13 Sawblade Bi-Metal 65x50mm<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-23494 status-publish instock product_cat-hout-metaal-en product_cat-sets-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-en product_cat-sl-slm-hout-metaal-en product_cat-sl-slm-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl95-set-hout-metaal-bim\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-450x450.png\" class=\"wp-image-23498 avia-img-lazy-loading-23498 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL95.png 1772w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL95 SET Wood-Metal BIM<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-23504 status-publish instock product_cat-hout-metaal-en product_cat-sets-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-en product_cat-sl-slm-hout-metaal-en product_cat-sl-slm-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl96-set-hout-metaal-bim-hcs\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-450x450.png\" class=\"wp-image-23508 avia-img-lazy-loading-23508 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL96.png 1772w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL96 SET Wood-Metal BIM \/ HCS<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<li class=\"product type-product post-23514 status-publish instock product_cat-hout-metaal-en product_cat-sets-en product_cat-sl-en product_cat-sl-slm-en product_cat-sl-slm-hout-en product_cat-sl-slm-hout-metaal-en product_cat-sl-slm-sets-en product_cat-wood has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/en\/product\/sl99-set-hout-metaal-bim-hcs\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-450x450.png\" class=\"wp-image-23518 avia-img-lazy-loading-23518 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2026\/08\/Qblades-SL99.png 1772w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">SL99 SET Wood-Metal BIM \/ HCS<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n<\/ul><\/div><\/div><div class=\"clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-4776","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assortment - WOOD-METAL - Qblades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qblades.nl\/en\/assortiment-metaal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assortment - WOOD-METAL - Qblades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qblades.nl\/en\/assortiment-metaal\/\" \/>\n<meta property=\"og:site_name\" content=\"Qblades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/qbladescom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-04T12:51:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/en\\\/assortiment-metaal\\\/\",\"url\":\"https:\\\/\\\/qblades.nl\\\/en\\\/assortiment-metaal\\\/\",\"name\":\"Assortment - WOOD-METAL - Qblades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\"},\"datePublished\":\"2015-05-01T07:50:10+00:00\",\"dateModified\":\"2020-03-04T12:51:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/en\\\/assortiment-metaal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qblades.nl\\\/en\\\/assortiment-metaal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/en\\\/assortiment-metaal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qblades.nl\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assortment &#8211; WOOD-METAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"name\":\"Qblades\",\"description\":\"importeur en distributeur van Multitool zaagbladen en accessoires\",\"publisher\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qblades.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\",\"name\":\"Qblades\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"contentUrl\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"width\":2840,\"height\":1420,\"caption\":\"Qblades\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/qbladescom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/qblades\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assortment - WOOD-METAL - Qblades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qblades.nl\/en\/assortiment-metaal\/","og_locale":"en_US","og_type":"article","og_title":"Assortment - WOOD-METAL - Qblades","og_url":"https:\/\/qblades.nl\/en\/assortiment-metaal\/","og_site_name":"Qblades","article_publisher":"https:\/\/www.facebook.com\/qbladescom\/","article_modified_time":"2020-03-04T12:51:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/qblades.nl\/en\/assortiment-metaal\/","url":"https:\/\/qblades.nl\/en\/assortiment-metaal\/","name":"Assortment - WOOD-METAL - Qblades","isPartOf":{"@id":"https:\/\/qblades.nl\/#website"},"datePublished":"2015-05-01T07:50:10+00:00","dateModified":"2020-03-04T12:51:06+00:00","breadcrumb":{"@id":"https:\/\/qblades.nl\/en\/assortiment-metaal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qblades.nl\/en\/assortiment-metaal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/qblades.nl\/en\/assortiment-metaal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qblades.nl\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Assortment &#8211; WOOD-METAL"}]},{"@type":"WebSite","@id":"https:\/\/qblades.nl\/#website","url":"https:\/\/qblades.nl\/","name":"Qblades","description":"importeur en distributeur van Multitool zaagbladen en accessoires","publisher":{"@id":"https:\/\/qblades.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qblades.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/qblades.nl\/#organization","name":"Qblades","url":"https:\/\/qblades.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/","url":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","contentUrl":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","width":2840,"height":1420,"caption":"Qblades"},"image":{"@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/qbladescom\/","https:\/\/www.linkedin.com\/company\/qblades"]}]}},"_links":{"self":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/pages\/4776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/comments?post=4776"}],"version-history":[{"count":24,"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/pages\/4776\/revisions"}],"predecessor-version":[{"id":12586,"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/pages\/4776\/revisions\/12586"}],"wp:attachment":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/media?parent=4776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}