{"id":1968,"count":4,"description":"","link":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/","name":"\u00d8 210","slug":"o-210","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00d8 210 Archieven - Qblades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d8 210 Archieven - Qblades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/\" \/>\n<meta property=\"og:site_name\" content=\"Qblades\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/en\\\/product-categorie\\\/o-210\\\/\",\"url\":\"https:\\\/\\\/qblades.nl\\\/en\\\/product-categorie\\\/o-210\\\/\",\"name\":\"\u00d8 210 Archieven - Qblades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/en\\\/product-categorie\\\/o-210\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/en\\\/product-categorie\\\/o-210\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qblades.nl\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d8 210\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"name\":\"Qblades\",\"description\":\"importeur en distributeur van Multitool zaagbladen en accessoires\",\"publisher\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qblades.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\",\"name\":\"Qblades\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"contentUrl\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"width\":2840,\"height\":1420,\"caption\":\"Qblades\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/qbladescom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/qblades\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d8 210 Archieven - Qblades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/","og_locale":"en_US","og_type":"article","og_title":"\u00d8 210 Archieven - Qblades","og_url":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/","og_site_name":"Qblades","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/","url":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/","name":"\u00d8 210 Archieven - Qblades","isPartOf":{"@id":"https:\/\/qblades.nl\/#website"},"breadcrumb":{"@id":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/qblades.nl\/en\/product-categorie\/o-210\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qblades.nl\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"\u00d8 210"}]},{"@type":"WebSite","@id":"https:\/\/qblades.nl\/#website","url":"https:\/\/qblades.nl\/","name":"Qblades","description":"importeur en distributeur van Multitool zaagbladen en accessoires","publisher":{"@id":"https:\/\/qblades.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qblades.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/qblades.nl\/#organization","name":"Qblades","url":"https:\/\/qblades.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/","url":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","contentUrl":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","width":2840,"height":1420,"caption":"Qblades"},"image":{"@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/qbladescom\/","https:\/\/www.linkedin.com\/company\/qblades"]}]}},"_links":{"self":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/product_cat\/1968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/qblades.nl\/en\/wp-json\/wp\/v2\/product?product_cat=1968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}