{"id":17050,"date":"2024-03-28T13:56:16","date_gmt":"2024-03-28T12:56:16","guid":{"rendered":"https:\/\/qblades.nl\/?post_type=product&#038;p=17050"},"modified":"2026-03-19T14:35:44","modified_gmt":"2026-03-19T13:35:44","slug":"qrc1312-reciprozaagblad","status":"publish","type":"product","link":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/","title":{"rendered":"QRC1312 &#8211; Lame de scie sabre &#8211; 302mm TPI: 6"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-q64l19-30b51361b9828d3e24abdb747ebe908d\">\n.flex_column.av-q64l19-30b51361b9828d3e24abdb747ebe908d{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-q64l19-30b51361b9828d3e24abdb747ebe908d av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-kbt2kwvb-647f5b2ff18d2e1a6a7e25d2225d2614 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>QRC1312 &#8211; Lame de scie sabre<\/h1>\n<\/div><\/section><br \/>\n<div  class='tabcontainer av-kbt1fdtt-570302c26c136ee73934f54c4eaf7250 top_tab  avia-builder-el-2  el_after_av_textblock  el_before_av_hr ' role='tablist'>\n<section class='av_tab_section av_tab_section av-ugzj93-f6d6401cfcfff60d7e72607f6b6f9c45'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab active_tab' role='tab' tabindex='0' data-fake-id='#tab-id-1' aria-controls='tab-id-1-content'  itemprop=\"headline\" >Description<\/div><div id='tab-id-1-content' class='tab_content active_tab_content' aria-hidden=\"false\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><p data-start=\"426\" data-end=\"527\">La lame de scie sabre QRC1312 garantit des coupes rapides dans le bois et le m\u00e9tal.<\/p>\n<ul data-start=\"530\" data-end=\"806\">\n<li data-start=\"530\" data-end=\"622\">Grand espacement des dents et dents dentel\u00e9es pour une coupe rapide et efficace.<\/li>\n<li data-start=\"625\" data-end=\"735\">\u00c9paisseur moyenne (1,27 mm) assurant un \u00e9quilibre parfait entre vitesse, flexibilit\u00e9 et stabilit\u00e9.<\/li>\n<li data-start=\"738\" data-end=\"806\">Compatible avec toutes les scies sabres \u00e0 emmanchement en S.<\/li>\n<\/ul>\n<p>Engrenage: 6tpi<br \/>\nLongueur: 302mm \/ 12&#8243;<br \/>\n\u00c9paisseur: 1,27mm<\/p>\n<p>\u00c0 utiliser comme : Bosch S1411DF<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16962\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6.png 152w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16997\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers.png 1000w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><\/p>\n<\/div><\/div><\/section>\n<section class='av_tab_section av_tab_section av-jp5o0t-ed7407fd516298d66a34e3610def0c64'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab' role='tab' tabindex='0' data-fake-id='#tab-id-2' aria-controls='tab-id-2-content'  itemprop=\"headline\" >Dealers<\/div><div id='tab-id-2-content' class='tab_content' aria-hidden=\"true\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><p><a href=\"\/dealer-popup\/?iframe=true&amp;width=100%&amp;height=100%\" rel=\"lightbox\">Voir et trouver un revendeur<\/a><\/p>\n<\/div><\/div><\/section>\n<\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e\">\n#top .hr.hr-invisible.av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e hr-invisible  avia-builder-el-3  el_after_av_tab_container  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kbt7ed44-0c3712b76d2b77f294d6162484d6513c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h5>Disponible en:<\/h5>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e\">\n#top .hr.hr-invisible.av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e hr-invisible  avia-builder-el-5  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kbt2kwvb-647f5b2ff18d2e1a6a7e25d2225d2614 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><table class=\"productcodes\">\n<tbody>\n<tr>\n<td>5ST<\/td>\n<td>EAN: 8718627385135<br \/>\nQBL385135<\/td>\n<\/tr>\n<tr>\n<td>50ST<\/td>\n<td>EAN: 8718627385784<br \/>\nQBL385784<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc\">\n.flex_column.av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc av_one_half  avia-builder-el-7  el_after_av_one_half  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ltzmtcut-1c10e512065336b2f0a4ce2a9521140e\">\n#top .avia-gallery.av-ltzmtcut-1c10e512065336b2f0a4ce2a9521140e .avia-gallery-thumb a{\nwidth:50%;\n}\n<\/style>\n<div  class='avia-gallery av-ltzmtcut-1c10e512065336b2f0a4ce2a9521140e avia_animate_when_visible  avia-builder-el-8  avia-builder-el-no-sibling  animations_off av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/\"><a class='avia-gallery-big fakeLightbox avianolink noLightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-onclick='1' title='QRC1312' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-17057 avia-img-lazy-loading-not-17057\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png\" title='QRC1312' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-100x100.png 100w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/span><\/a><div class='avia-gallery-thumb'><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png' class='first_thumb avianolink noLightbox ' data-onclick='1' title='QRC1312'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-17057 avia-img-lazy-loading-not-17057\"   src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png\" width=\"300\" height=\"300\"  title='QRC1312' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-17057 avia-img-lazy-loading-17057\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png\" title='QRC1312' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><\/a><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs.png' class='avianolink noLightbox ' data-onclick='2' title='QRC1312-5pcs'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-17053 avia-img-lazy-loading-not-17053\"   src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-300x300.png\" width=\"300\" height=\"300\"  title='QRC1312-5pcs' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-17053 avia-img-lazy-loading-17053\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs.png\" title='QRC1312-5pcs' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312-5pcs-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><\/a><\/div><\/div><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b\">\n#top .hr.hr-invisible.av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b{\nheight:100px;\n}\n<\/style>\n<div  class='hr av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b hr-invisible  avia-builder-el-9  el_after_av_one_half  el_before_av_product_upsells '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  class='av-woo-product-related-upsells av-lceapp-35f469ec0610a8cd6d78c6217f9b09c1  avia-builder-el-10  el_after_av_hr  avia-builder-el-last '><div class='product_column product_column_4'>\n\t<section class=\"related products\">\n\n\t\t\t\t\t<h2>Produits similaires<\/h2>\n\t\t\t\t<ul class=\"products columns-4\">\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17037 status-publish first instock product_cat-recipro-hout-met-spijkers-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc1309-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-450x450.png\" class=\"wp-image-17045 avia-img-lazy-loading-17045 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1309.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1309 &#8211; Lame de scie sabre &#8211; 228mm TPI: 6<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17251 status-publish instock product_cat-recipro-medium-metaal-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc5106-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-450x450.png\" class=\"wp-image-17258 avia-img-lazy-loading-17258 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC5106.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC5106 &#8211; Lame de scie sabre &#8211; 150mm TPI: 14<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17013 status-publish instock product_cat-recipro-hout-met-spijkers-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc1112-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-450x450.png\" class=\"wp-image-17020 avia-img-lazy-loading-17020 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1112.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1112 &#8211; Lame de scie sabre &#8211; 300MM TPI: 5\/8<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-16992 status-publish last instock product_cat-recipro-hout-met-spijkers-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc1109-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-450x450.png\" class=\"wp-image-17004 avia-img-lazy-loading-17004 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1109.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1109 &#8211; Lame de scie sabre &#8211; 228mm TPI: 5\/8<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t<\/ul>\n\n\t<\/section>\n\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":17057,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1855,1839],"product_tag":[],"class_list":["post-17050","product","type-product","status-publish","has-post-thumbnail","product_cat-recipro-hout-met-spijkers-fr","product_cat-recipro-fr","pa_merk-black-decker-fr","pa_merk-dewalt-fr","pa_merk-parkside-fr","pa_merk-stanley","first","instock","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QRC1312 - Lame de scie sabre - 302mm TPI: 6 - Qblades<\/title>\n<meta name=\"description\" content=\"Met de QRC1309 krijg je snel gebogen zaagsneden in zowel hout als metaal met ons reciprozaagblad. Met grote tandafstand en gezette tanden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QRC1312 - Lame de scie sabre - 302mm TPI: 6 - Qblades\" \/>\n<meta property=\"og:description\" content=\"Met de QRC1309 krijg je snel gebogen zaagsneden in zowel hout als metaal met ons reciprozaagblad. Met grote tandafstand en gezette tanden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/\" \/>\n<meta property=\"og:site_name\" content=\"Qblades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/qbladescom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T13:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/\",\"url\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/\",\"name\":\"QRC1312 - Lame de scie sabre - 302mm TPI: 6 - Qblades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QRC1312.png\",\"datePublished\":\"2024-03-28T12:56:16+00:00\",\"dateModified\":\"2026-03-19T13:35:44+00:00\",\"description\":\"Met de QRC1309 krijg je snel gebogen zaagsneden in zowel hout als metaal met ons reciprozaagblad. Met grote tandafstand en gezette tanden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QRC1312.png\",\"contentUrl\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QRC1312.png\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc1312-reciprozaagblad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/qblades.nl\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"QRC1312 &#8211; Lame de scie sabre &#8211; 302mm TPI: 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"name\":\"Qblades\",\"description\":\"importeur en distributeur van Multitool zaagbladen en accessoires\",\"publisher\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qblades.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\",\"name\":\"Qblades\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"contentUrl\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"width\":2840,\"height\":1420,\"caption\":\"Qblades\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/qbladescom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/qblades\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QRC1312 - Lame de scie sabre - 302mm TPI: 6 - Qblades","description":"Met de QRC1309 krijg je snel gebogen zaagsneden in zowel hout als metaal met ons reciprozaagblad. Met grote tandafstand en gezette tanden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/","og_locale":"fr_FR","og_type":"article","og_title":"QRC1312 - Lame de scie sabre - 302mm TPI: 6 - Qblades","og_description":"Met de QRC1309 krijg je snel gebogen zaagsneden in zowel hout als metaal met ons reciprozaagblad. Met grote tandafstand en gezette tanden.","og_url":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/","og_site_name":"Qblades","article_publisher":"https:\/\/www.facebook.com\/qbladescom\/","article_modified_time":"2026-03-19T13:35:44+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/","url":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/","name":"QRC1312 - Lame de scie sabre - 302mm TPI: 6 - Qblades","isPartOf":{"@id":"https:\/\/qblades.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/#primaryimage"},"image":{"@id":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/#primaryimage"},"thumbnailUrl":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png","datePublished":"2024-03-28T12:56:16+00:00","dateModified":"2026-03-19T13:35:44+00:00","description":"Met de QRC1309 krijg je snel gebogen zaagsneden in zowel hout als metaal met ons reciprozaagblad. Met grote tandafstand en gezette tanden.","breadcrumb":{"@id":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/#primaryimage","url":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png","contentUrl":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1312.png","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/qblades.nl\/fr\/product\/qrc1312-reciprozaagblad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qblades.nl\/fr\/homepage\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/qblades.nl\/products\/"},{"@type":"ListItem","position":3,"name":"QRC1312 &#8211; Lame de scie sabre &#8211; 302mm TPI: 6"}]},{"@type":"WebSite","@id":"https:\/\/qblades.nl\/#website","url":"https:\/\/qblades.nl\/","name":"Qblades","description":"importeur en distributeur van Multitool zaagbladen en accessoires","publisher":{"@id":"https:\/\/qblades.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qblades.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/qblades.nl\/#organization","name":"Qblades","url":"https:\/\/qblades.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/","url":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","contentUrl":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","width":2840,"height":1420,"caption":"Qblades"},"image":{"@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/qbladescom\/","https:\/\/www.linkedin.com\/company\/qblades"]}]}},"_links":{"self":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product\/17050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/media\/17057"}],"wp:attachment":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/media?parent=17050"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=17050"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=17050"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=17050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}