{"id":17108,"date":"2024-04-02T10:20:17","date_gmt":"2024-04-02T08:20:17","guid":{"rendered":"https:\/\/qblades.nl\/?post_type=product&#038;p=17108"},"modified":"2026-03-19T14:40:04","modified_gmt":"2026-03-19T13:40:04","slug":"qrc2508-reciprozaagblad","status":"publish","type":"product","link":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/","title":{"rendered":"QRC2508 &#8211; Lame de scie sabre &#8211; 203mm TPI: 6\/10"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-q64l19-30b51361b9828d3e24abdb747ebe908d\">\n.flex_column.av-q64l19-30b51361b9828d3e24abdb747ebe908d{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-q64l19-30b51361b9828d3e24abdb747ebe908d av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-kbt2kwvb-647f5b2ff18d2e1a6a7e25d2225d2614 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>QRC2508 &#8211; Lame de scie sabre<\/h1>\n<\/div><\/section><br \/>\n<div  class='tabcontainer av-kbt1fdtt-570302c26c136ee73934f54c4eaf7250 top_tab  avia-builder-el-2  el_after_av_textblock  el_before_av_hr ' role='tablist'>\n<section class='av_tab_section av_tab_section av-v8wrkh-04a4bfda464861c1661cb3f903ec8f92'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab active_tab' role='tab' tabindex='0' data-fake-id='#tab-id-1' aria-controls='tab-id-1-content'  itemprop=\"headline\" >Description<\/div><div id='tab-id-1-content' class='tab_content active_tab_content' aria-hidden=\"false\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><p data-start=\"407\" data-end=\"491\">Cette lame de scie sabre permet des d\u00e9coupes dans les mat\u00e9riaux fins et \u00e9pais.<\/p>\n<ul data-start=\"494\" data-end=\"791\">\n<li data-start=\"494\" data-end=\"617\">L&#8217;espacement croissant des dents offre une coupe puissante et rapide, m\u00eame \u00e0 travers des mat\u00e9riaux de densit\u00e9 variable.<\/li>\n<li data-start=\"620\" data-end=\"729\">Les dents sont sp\u00e9cialement con\u00e7ues pour couper divers types de bois et de m\u00e9taux, y compris l&#8217;aluminium.<\/li>\n<li data-start=\"732\" data-end=\"791\">Convient \u00e0 toutes les scies sabres \u00e0 emmanchement en S.<\/li>\n<\/ul>\n<p>Engrenage: 6\/10tpi<br \/>\nLongueur: 203mm \/ 8&#8243;<br \/>\n\u00c9paisseur: 1,3mm<\/p>\n<p>\u00c0 utiliser comme : Bosch S3456XF<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16958\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-10-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-10-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-10-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-10-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-10-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/tpi6-10.png 152w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16997\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/qblades_icoon_houtspijkers.png 1000w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-12817\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-80x80.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2020\/02\/icon-metaal.png 500w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><\/p>\n<\/div><\/div><\/section>\n<section class='av_tab_section av_tab_section av-jp5o0t-ed7407fd516298d66a34e3610def0c64'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='tab' role='tab' tabindex='0' data-fake-id='#tab-id-2' aria-controls='tab-id-2-content'  itemprop=\"headline\" >Dealers<\/div><div id='tab-id-2-content' class='tab_content' aria-hidden=\"true\"><div class='tab_inner_content invers-color'  itemprop=\"text\" ><p><a href=\"\/dealer-popup\/?iframe=true&amp;width=100%&amp;height=100%\" rel=\"lightbox\">Voir et trouver un revendeur<\/a><\/p>\n<\/div><\/div><\/section>\n<\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e\">\n#top .hr.hr-invisible.av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e hr-invisible  avia-builder-el-3  el_after_av_tab_container  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kbt7ed44-0c3712b76d2b77f294d6162484d6513c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h5>Disponible en:<\/h5>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e\">\n#top .hr.hr-invisible.av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kbtaupt4-3c6cce770452dd73ad7b5f9f0f3b331e hr-invisible  avia-builder-el-5  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kbt2kwvb-647f5b2ff18d2e1a6a7e25d2225d2614 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><table class=\"productcodes\">\n<tbody>\n<tr>\n<td>5ST<\/td>\n<td>EAN: 8718627385173<br \/>\nQBL385173<\/td>\n<\/tr>\n<tr>\n<td>50ST<\/td>\n<td>EAN: 8718627385807<br \/>\nQBL385807<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc\">\n.flex_column.av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1pu65el-45ae382f9ddcdccc5eb0d2eea4f689cc av_one_half  avia-builder-el-7  el_after_av_one_half  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ltzmtcut-ffeaa4d48a8d1084c48e560b98667795\">\n#top .avia-gallery.av-ltzmtcut-ffeaa4d48a8d1084c48e560b98667795 .avia-gallery-thumb a{\nwidth:50%;\n}\n<\/style>\n<div  class='avia-gallery av-ltzmtcut-ffeaa4d48a8d1084c48e560b98667795 avia_animate_when_visible  avia-builder-el-8  avia-builder-el-no-sibling  animations_off av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/\"><a class='avia-gallery-big fakeLightbox avianolink noLightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-onclick='1' title='QRC2508' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-17115 avia-img-lazy-loading-not-17115\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png\" title='QRC2508' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-100x100.png 100w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/span><\/a><div class='avia-gallery-thumb'><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png' class='first_thumb avianolink noLightbox ' data-onclick='1' title='QRC2508'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-17115 avia-img-lazy-loading-not-17115\"   src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png\" width=\"300\" height=\"300\"  title='QRC2508' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-17115 avia-img-lazy-loading-17115\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png\" title='QRC2508' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><\/a><a href=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1030x1030.png\" data-srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs.png 2000w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs.png' class='avianolink noLightbox ' data-onclick='2' title='QRC2508-5pcs'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-17111 avia-img-lazy-loading-not-17111\"   src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-300x300.png\" width=\"300\" height=\"300\"  title='QRC2508-5pcs' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-17111 avia-img-lazy-loading-17111\"  width=\"2000\" height=\"2000\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs.png\" title='QRC2508-5pcs' alt='' srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs.png 2000w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508-5pcs-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><\/a><\/div><\/div><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b\">\n#top .hr.hr-invisible.av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b{\nheight:100px;\n}\n<\/style>\n<div  class='hr av-kbt2n7kt-0d3ea9ac35dcc40d6a2160dd04ab988b hr-invisible  avia-builder-el-9  el_after_av_one_half  el_before_av_product_upsells '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  class='av-woo-product-related-upsells av-lceapp-35f469ec0610a8cd6d78c6217f9b09c1  avia-builder-el-10  el_after_av_hr  avia-builder-el-last '><div class='product_column product_column_4'>\n\t<section class=\"related products\">\n\n\t\t\t\t\t<h2>Produits similaires<\/h2>\n\t\t\t\t<ul class=\"products columns-4\">\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-16840 status-publish first instock product_cat-recipro-hout-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc0109-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-450x450.png\" class=\"wp-image-16895 avia-img-lazy-loading-16895 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-2048x2048.png 2048w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC0109v8-100x100.png 100w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC0109 &#8211; Lame de scie sabre &#8211; 240mm TPI: 5<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17153 status-publish instock product_cat-recipro-alleskunners-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc2212-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-450x450.png\" class=\"wp-image-17156 avia-img-lazy-loading-17156 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2212.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC2212 &#8211; Lame de scie sabre &#8211; 300mm TPI: 8\/10<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17062 status-publish instock product_cat-recipro-hout-met-spijkers-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc1406-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-450x450.png\" class=\"wp-image-17069 avia-img-lazy-loading-17069 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/03\/QRC1406.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1406 &#8211; Lame de scie sabre &#8211; 150mm TPI: 10<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t\t\t\t<li class=\"product type-product post-17092 status-publish last instock product_cat-recipro-hout-met-spijkers-fr product_cat-recipro-fr has-post-thumbnail product-type-simple\">\n\t<div class='inner_product main_color wrapped_style noLightbox  av-product-class-no_button'><a href=\"https:\/\/qblades.nl\/fr\/product\/qrc1512-reciprozaagblad\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail_container\"><img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"450\" src=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-450x450.png\" class=\"wp-image-17082 avia-img-lazy-loading-17082 attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-450x450.png 450w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-300x300.png 300w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-1030x1030.png 1030w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-80x80.png 80w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-768x768.png 768w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-1536x1536.png 1536w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-36x36.png 36w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-180x180.png 180w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-1500x1500.png 1500w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-705x705.png 705w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-120x120.png 120w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409-100x100.png 100w, https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC1409.png 2000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><span class=\"cart-loading\"><\/span><\/div><div class='inner_product_header'><div class='avia-arrow'><\/div><div class='inner_product_header_table'><div class='inner_product_header_cell'><h2 class=\"woocommerce-loop-product__title\">QRC1512 &#8211; Lame de scie sabre &#8211; 304mm TPI: 10\/14<\/h2>\n<\/div><\/div><\/div><\/a><\/div><\/li>\n\n\t\t\t\n\t\t<\/ul>\n\n\t<\/section>\n\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":17115,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1852,1839],"product_tag":[],"class_list":["post-17108","product","type-product","status-publish","has-post-thumbnail","product_cat-recipro-alleskunners-fr","product_cat-recipro-fr","pa_merk-black-decker-fr","pa_merk-dewalt-fr","pa_merk-parkside-fr","pa_merk-stanley","first","instock","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QRC2508 - Lame de scie sabre - 203mm TPI: 6\/10 - Qblades<\/title>\n<meta name=\"description\" content=\"De QRC2508 reciprozaagblad levert krachtige en snelle zaagsneden in zowel dik als dun materiaal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QRC2508 - Lame de scie sabre - 203mm TPI: 6\/10 - Qblades\" \/>\n<meta property=\"og:description\" content=\"De QRC2508 reciprozaagblad levert krachtige en snelle zaagsneden in zowel dik als dun materiaal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/\" \/>\n<meta property=\"og:site_name\" content=\"Qblades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/qbladescom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T13:40:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/\",\"url\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/\",\"name\":\"QRC2508 - Lame de scie sabre - 203mm TPI: 6\\\/10 - Qblades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/QRC2508.png\",\"datePublished\":\"2024-04-02T08:20:17+00:00\",\"dateModified\":\"2026-03-19T13:40:04+00:00\",\"description\":\"De QRC2508 reciprozaagblad levert krachtige en snelle zaagsneden in zowel dik als dun materiaal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/QRC2508.png\",\"contentUrl\":\"https:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/QRC2508.png\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/product\\\/qrc2508-reciprozaagblad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qblades.nl\\\/fr\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/qblades.nl\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"QRC2508 &#8211; Lame de scie sabre &#8211; 203mm TPI: 6\\\/10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#website\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"name\":\"Qblades\",\"description\":\"importeur en distributeur van Multitool zaagbladen en accessoires\",\"publisher\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qblades.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#organization\",\"name\":\"Qblades\",\"url\":\"https:\\\/\\\/qblades.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"contentUrl\":\"http:\\\/\\\/qblades.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/logo-qblades.png\",\"width\":2840,\"height\":1420,\"caption\":\"Qblades\"},\"image\":{\"@id\":\"https:\\\/\\\/qblades.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/qbladescom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/qblades\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QRC2508 - Lame de scie sabre - 203mm TPI: 6\/10 - Qblades","description":"De QRC2508 reciprozaagblad levert krachtige en snelle zaagsneden in zowel dik als dun materiaal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/","og_locale":"fr_FR","og_type":"article","og_title":"QRC2508 - Lame de scie sabre - 203mm TPI: 6\/10 - Qblades","og_description":"De QRC2508 reciprozaagblad levert krachtige en snelle zaagsneden in zowel dik als dun materiaal.","og_url":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/","og_site_name":"Qblades","article_publisher":"https:\/\/www.facebook.com\/qbladescom\/","article_modified_time":"2026-03-19T13:40:04+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/","url":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/","name":"QRC2508 - Lame de scie sabre - 203mm TPI: 6\/10 - Qblades","isPartOf":{"@id":"https:\/\/qblades.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/#primaryimage"},"image":{"@id":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/#primaryimage"},"thumbnailUrl":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png","datePublished":"2024-04-02T08:20:17+00:00","dateModified":"2026-03-19T13:40:04+00:00","description":"De QRC2508 reciprozaagblad levert krachtige en snelle zaagsneden in zowel dik als dun materiaal.","breadcrumb":{"@id":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/#primaryimage","url":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png","contentUrl":"https:\/\/qblades.nl\/wp-content\/uploads\/2024\/04\/QRC2508.png","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/qblades.nl\/fr\/product\/qrc2508-reciprozaagblad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qblades.nl\/fr\/homepage\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/qblades.nl\/products\/"},{"@type":"ListItem","position":3,"name":"QRC2508 &#8211; Lame de scie sabre &#8211; 203mm TPI: 6\/10"}]},{"@type":"WebSite","@id":"https:\/\/qblades.nl\/#website","url":"https:\/\/qblades.nl\/","name":"Qblades","description":"importeur en distributeur van Multitool zaagbladen en accessoires","publisher":{"@id":"https:\/\/qblades.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qblades.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/qblades.nl\/#organization","name":"Qblades","url":"https:\/\/qblades.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/","url":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","contentUrl":"http:\/\/qblades.nl\/wp-content\/uploads\/2022\/08\/logo-qblades.png","width":2840,"height":1420,"caption":"Qblades"},"image":{"@id":"https:\/\/qblades.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/qbladescom\/","https:\/\/www.linkedin.com\/company\/qblades"]}]}},"_links":{"self":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product\/17108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/media\/17115"}],"wp:attachment":[{"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/media?parent=17108"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=17108"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=17108"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/qblades.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=17108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}